{"id":7832,"date":"2024-03-29T21:14:17","date_gmt":"2024-03-29T21:14:17","guid":{"rendered":"http:\/\/whyfestival.com\/2021-edition\/"},"modified":"2024-03-29T21:31:00","modified_gmt":"2024-03-29T21:31:00","slug":"2021-edition","status":"publish","type":"page","link":"https:\/\/whyfestival.com\/it\/2021-edition\/","title":{"rendered":"2021"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;6024&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;13%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; color_overlay=&#8221;rgba(10,10,10,0)&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;350&#8243; bg_image_animation=&#8221;fade-in&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;mountains&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;26-28 novembre, 2021&#8243;][\/split_line_heading][vc_column_text]\n<h3>Perch\u00e9 amiamo condividere<br \/>\nPerch\u00e9 vogliamo imparare<br \/>\nPerch\u00e9 desideriamo ispirare<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(45,200,225,0.01)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffb514&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;I workshop&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23f572a8&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637429478488{margin-bottom: 5% !important;}&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][recent_posts style=&#8221;slider_multiple_visible&#8221; columns=&#8221;2&#8243; button_color=&#8221;Extra-Color-1&#8243; hover_shadow_type=&#8221;dark&#8221; category=&#8221;workshops-2021-it&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; image_loading=&#8221;default&#8221; blog_remove_post_date=&#8221;true&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; posts_per_page=&#8221;4&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;rgba(45,200,225,0.01)&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#2dc8e1&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Mostra&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23f572a8&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637429470734{margin-bottom: 5% !important;}&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][recent_posts style=&#8221;single_large_featured&#8221; large_featured_padding=&#8221;20%&#8221; button_color=&#8221;Accent-Color&#8221; bg_overlay=&#8221;solid_color&#8221; category=&#8221;exhibition-2021-it&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; image_loading=&#8221;default&#8221; blog_remove_post_date=&#8221;true&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; vertically_center_columns=&#8221;true&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2dc8e1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#2dc8e1&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Conferenze&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637429448391{margin-bottom: 5% !important;}&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][recent_posts style=&#8221;slider_multiple_visible&#8221; columns=&#8221;4&#8243; button_color=&#8221;Accent-Color&#8221; hover_shadow_type=&#8221;default&#8221; category=&#8221;talk-2021-it&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; image_loading=&#8221;default&#8221; posts_per_page=&#8221;18&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;Il programma&#8221; max_width=&#8221;500&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;minimal_flexible&#8221; tab_color=&#8221;Accent-Color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;26 novembre&#8221; id=&#8221;1711747749790-5&#8243; tab_id=&#8221;1711747749791-0&#8243;][vc_row_inner column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;18:30 &#8211; 20:00&#8243; col_2_content=&#8221;Inaugurazione della mostra di manifesti di Mauro Bubbico con concerto a cura di Pippolo Music School accompagnato da live drawing di Nicola Giorgio&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/super-manifesto\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;27 novembre&#8221; id=&#8221;1711747749839-8&#8243; tab_id=&#8221;1711747749840-5&#8243;][vc_row_inner column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;09:30 &#8211; 18:30&#8243; col_2_content=&#8221;Workshop: Animazione al dente&#8221; cta_1_text=&#8221;Register&#8221; cta_1_url=&#8221;https:\/\/www.facebook.com\/events\/313422820314163\/&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/animation-al-dente\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;11:00 &#8211; 16:00&#8243; col_2_content=&#8221;Workshop: Linocut per illustratori con Paola Lucrezi dal Il Bisonte&#8221; cta_1_text=&#8221;Register&#8221; cta_1_url=&#8221;https:\/\/www.facebook.com\/events\/257721713000858&#8243; url=&#8221;http:\/\/whyfestival.com\/it\/linocut-for-illustrators-with-paola-lucrezzi\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;11:00 &#8211; 16:00&#8243; col_2_content=&#8221;Workshop: RICAMI URBAN Workshop di ricamo creativo con Calimaia&#8221; cta_1_text=&#8221;Register&#8221; cta_1_url=&#8221;https:\/\/www.facebook.com\/events\/965802541004507\/&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/ricami-urbani-workshop-of-creative-embroidery-with-calimaia\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;14:00 &#8211; 16:00&#8243; col_2_content=&#8221;Workshop: Creare coinvolgenti UI animate con Invision Studio&#8221; cta_1_text=&#8221;Register&#8221; cta_1_url=&#8221;https:\/\/www.facebook.com\/events\/585093722609021&#8243; url=&#8221;http:\/\/whyfestival.com\/it\/create-engaging-ui-animations-with-invision-studio\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;15:00 &#8211; 15:30&#8243; col_2_content=&#8221;Illustrazione tra culturale e sociale&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/illustration-between-cultural-and-social\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;15:40 &#8211; 17:10&#8243; col_2_content=&#8221;Only the Brave &#8211; Quanto coraggio ci vuole per fare editoria indipendente nel 2021? Lungarno, Contrabbandiera Editrice e Friscospeaks presentano le propria realt\u00e0 esponendo le varie sfaccettature del mondo dell\u2019editoria indipendente&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/panel-discussion-only-the-brave\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;17:20 &#8211; 17:50&#8243; col_2_content=&#8221;Networking come progetto per l\u2019arte, da Gruppo11 a Drawingalive&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/networking-as-a-project-for-art-from-gruppo11-to-drawingalive\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;18:00 &#8211; 19:30&#8243; col_2_content=&#8221;La tregua dei mondi &#8211; Incontro con Costanza Ciattini e sessione di collage collettivo&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/the-truce-of-the-worlds\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;28 novembre&#8221; id=&#8221;1711747749979-4&#8243; tab_id=&#8221;1711747749979-1&#8243;][vc_row_inner column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;15:00 &#8211; 15:30&#8243; col_2_content=&#8221;Missive Selvatiche: una resistenza artistica&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/missive-selvatiche-an-artistic-resistance\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;15:30 &#8211; 16:00&#8243; col_2_content=&#8221;Calimaia in the city. Urban Art per riqualificare e sensibilizzare la citt\u00e0 riguardo alle tematiche collettive&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/calimaia-in-the-city\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;16:00 &#8211; 16:30&#8243; col_2_content=&#8221;Hearing You &#8211; L&#8217;illustratore Simone Massoni e la lettering artist Maria Chiara Fantini parlano dei loro recenti progetti in collaborazione&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/hearing-you\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;h3&#8243; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;16:40 &#8211; 18:00&#8243; col_2_content=&#8221;Outside the box &#8211; Panel su collaborazioni tra docenti+studenti con Tommaso Bovo, Susanna Cerri, Laura Moretti&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/panel-discussion-outside-the-box\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;18:10-18:40&#8243; col_2_content=&#8221;Presentazione del libro &#8220;Libri con figure&#8220; con Andrea Rauch&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/libri-con-figure-book-presentation-of-andrea-rauch\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;p&#8221; open_new_tab=&#8221;true&#8221; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;18:50-19:30&#8243; col_2_content=&#8221;TypeCampus e la community del type: dire, fare, studiare con Debora Manetti, Shrishti Vajpai, Isabella Ahmadzadeh di Zetafonts&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/typecampus-and-the-community-of-type\/&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;large_middle&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;h3&#8243; col_3_text_element=&#8221;p&#8221; cta_1_open_new_tab=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;default&#8221; hover_color=&#8221;accent-color&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;regular&#8221; col_1_content=&#8221;19:30-20:30&#8243; col_2_content=&#8221;Raise My Type: blind tasting edition&#8221; url=&#8221;http:\/\/whyfestival.com\/it\/raise-my-type\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;I partecipanti&#8221; max_width=&#8221;500&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7605&#8243; bio_alt_image_url=&#8221;7603&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Mauro Bubbico&#8221; job_position=&#8221;Mostra &#8220;Super Manifesto&#8220;&#8221; social_link_1=&#8221;https:\/\/www.maurobubbico.it\/&#8221; social_link_2=&#8221;https:\/\/www.instagram.com\/mauro_bubbico\/&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Mauro Bubbico \u00e8 nato a Montescaglioso (Matera) dove vive e lavora dal 1986 come grafico professionista. Tra i campi d\u2019intervento privilegia il design finalizzato all&#8217;educazione sociale e alla sostenibilit\u00e0 ambientale. Nel corso degli anni i suoi interessi, le ricerche sui luoghi e i loro abitanti lo hanno portato alla definizione di un linguaggio grafico efficace e contemporaneo adatto a raccontarli e a valorizzarli per favorire lo sviluppo umano, economico e culturale, convinto che la cultura grafica \u00e8, prima di tutto, capacit\u00e0 di costruire grandi narrazioni. \u00c8 docente di Progettazione Grafica all\u2019Isia di Urbino, all&#8217;Isia di Faenza, all\u2019Abadir di Catania e alla Free University Bozen-Bolzano.<br \/>\n\u00c8 socio Aiap (Associazione italiana design della comunicazione visiva) e membro AGI (Alliance Graphique Internationale).&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_icon_2=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7607&#8243; bio_alt_image_url=&#8221;7609&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Marco Dalmasso&#8221; job_position=&#8221;L\u2019Infallibile Metodo&#8221; social_link_1=&#8221;https:\/\/www.pippolomusicschool.it\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Marco Dalmasso in arte Ghiaccioli e Branzini \u00e8 un Producer residente a Firenze. Negli anni ha affinato quello che si pu\u00f2 definire uno stile inconfondibile. Se la base \u00e8 sempre la musica elettronica, le contaminazioni invece sono molteplici: rimandi al Blues, al Jazz e alla musica folk. La sperimentazione, la commistione tra generi e le collaborazioni con tantissimi musicisti fanno di Ghiaccioli e Branzini una figura unica nel panorama italiano. Nel 2010 Con il producer Tulioxi forma il combo Global Kan Kan con cui oltre a partecipare a numerosi Festival in Italia e in Europa realizza diverse uscite discografiche: Clatter records, Multivitamins (Uk), Materiali Sonori.<br \/>\nDal 2012 ad oggi Ghiaccioli e Branzini \u00e8 attivo con numerosi progetti di interazione tra musica elettronica e musica suonata: Camillocromo Beat Band, Fanfara station, Hugolini. Negli ultimi anni ha composto diverse colonne sonore per Spot televisivi, Fashion Show e per campagne pubblicitarie collaborando con diversi brand tra i quali quali:<br \/>\nNoris, Superduper Hats, Gucci, Levi\u2019s, Guess, Archivio Personale, Sebago, Saks Fifth Avenue e molti altri.<\/p>\n<p>Nel 2018 vince il premio italiano Folkint come miglior progetto di rivisitazione elettronica della tradizione Folk.<br \/>\nNel 2019 con il progetto Fanfara Station vince il premio Andrea Parodi, il pi\u00f9 importante contest italiano dedicato alla World Music&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7613&#8243; bio_alt_image_url=&#8221;7611&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Charles Ferris&#8221; job_position=&#8221;L\u2019Infallibile Metodo&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Charles Ferris, canadese nato a Toronto, trombettista ed etnomusicologo, arriva in Italia come borsista Fulbright con una ricerca sulle tradizioni e i canti del sud. Da quando ha iniziato a studiare musica classica, quarant&#8217;anni fa negli Stati uniti, ha attraversato quasi ogni genere musicale. Come giovane studente \u00e8 stato premiato a New York City come solista al concorso nazionale della Music Teachers National Association. A 18 anni ha vinto The Louisville Orchestra\u2019s Young Artist Competition e ha suonato come solista con la orchestra che ha fatto la storia della musica del \u2018900 americano.<br \/>\nCon un\u2019orchestra afro-cubana ha girato tutti i locali di salsa di San Francisco mentre di giorno studiava il jazz e l\u2019improvvisazione contemporanea con Myra Melford, Fred Frith, Henry Threadgill e Steve Coleman.<br \/>\nHa suonato in numerosi progetti di musica balcanica, rock, jazz, funk, blues, ed ensemble di musica improvvisata contemporanea e musica popolare. Il filo rosso che unisce la diversa gamma di generi e progetti musicali in cui ha suonato \u00e8 la ricerca, l\u2019originalit\u00e0 e una certa attitudine all\u2019improvvisazione.<br \/>\nIn Italia dal 2006, ha collaborato con centinaia di musicisti in numerose band: i Sineterra, Marcello Giannini, Badara Sek, Francesco Forni, E Zezi, e ha iniziato un lungo percorso di studio della musica classica e popolare tunisina a fianco a Marzouk Mejri con cui ha fondato, Fanfara Station nel 2015, assieme al producer e beat-maker Ghiaccioli e Branzini.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_link_1=&#8221;https:\/\/www.pippolomusicschool.it\/&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7242&#8243; bio_alt_image_url=&#8221;7244&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Costanza Ciattini&#8221; social_link_1=&#8221;https:\/\/costanzaciattini.com\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Costanza Ciattini \u00e8 un\u2019artista freelance con base a Firenze. Laureata in design presso ISIA Firenze, oltre ad occuparsi di allestimenti di stand e set insieme ad Elisabetta Nazzi Atelier, crea opere d\u2019arte usando la tecnica del collage tridimensionale. Negli anni ha esposto le sue opere presso la galleria Cartavetra, lo Student Hotel e per eventi privati. Ha inoltre creato illustrazioni per riviste e libri indipendenti.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7209&#8243; bio_alt_image_url=&#8221;7211&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Irene Giusti | Calimaia Colletivo&#8221; job_position=&#8221;Workshop: Ricamo urbano&#8221; team_member_bio=&#8221;Irene Giusti, laureata in Architettura e Design della Comunicazione all&#8217;ISIA di Firenze, oggi lavora come Graphic Designer. Durante il lockdown dedica le giornate alla macchina da cucire e alla creazione di cappelli che condivide sulla pagina Instagram di Capa.<br \/>\nCalimaia collettivo \u00e8 una rete di giovani professionisti grafici ed illustratori che organizza eventi creativi, come workshop, mostre collettive, live painting e chi pi\u00f9 ne ha pi\u00f9 ne metta! Collettivo per noi significa scambio e collaborazione: Calimaia nasce con il fine di creare un punto di incontro fra i professionisti creativi e dare loro visibilit\u00e0 attraverso l\u2019organizzazione di eventi sul territorio di Firenze e non solo!&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/calimaia_collettivo\/&#8221; social_link_2=&#8221;https:\/\/www.instagram.com\/capaheadwear&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221; social_icon_2=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7215&#8243; bio_alt_image_url=&#8221;7213&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Irene Manetti | Calimaia Colletivo&#8221; job_position=&#8221;Workshop: Ricamo urbano&#8221; team_member_bio=&#8221;Visual designer fiorentina, Irene ha studiato Design della Comunicazione a Milano, dove ha vissuto cinque anni. Progettista curiosa, \u00e8 amante delle linee semplici, dell\u2019armonia tra pieni e vuoti e della geometria. Nei suoi progetti personali, adotta spesso un linguaggio ibrido tra grafica e illustrazione.<br \/>\nCalimaia collettivo \u00e8 una rete di giovani professionisti grafici ed illustratori che organizza eventi creativi, come workshop, mostre collettive, live painting e chi pi\u00f9 ne ha pi\u00f9 ne metta! Collettivo per noi significa scambio e collaborazione: Calimaia nasce con il fine di creare un punto di incontro fra i professionisti creativi e dare loro visibilit\u00e0 attraverso l\u2019organizzazione di eventi sul territorio di Firenze e non solo!&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/calimaia_collettivo\/&#8221; social_link_2=&#8221;https:\/\/www.instagram.com\/capaheadwear&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221; social_icon_2=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7181&#8243; bio_alt_image_url=&#8221;7183&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Gianluca Patti&#8221; job_position=&#8221;Workshop: Animazione al dente&#8221; team_member_bio=&#8221;Gianluca Patti \u00e8 un creativo che si occupa di illustrazione, storytelling e animazione. \u00c8 nato in Sicilia e si \u00e8 laureato al Biennio Specialistico in Illustrazione e Animazione dell&#8217;ISIA di Urbino. Attualmente di base a Firenze, trascorre le sue giornate disegnando come illustratore per lo studio di animazione Le Cube e sfrecciando per la citt\u00e0 con la sua fixie.&#8221; social_link_1=&#8221;instagram.com\/glcpatti&#8221; social_link_2=&#8221;gianlucapatti.art&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221; social_icon_2=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7189&#8243; bio_alt_image_url=&#8221;7187&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Bianca Sangalli Moretti&#8221; job_position=&#8221;Workshop: Animazione al dente&#8221; team_member_bio=&#8221;Bianca Sangalli Moretti \u00e8 un&#8217;illustratrice e autrice che vive a Firenze. Quando non \u00e8 sul campo da basket lavora come designer da Niceshit, uno studio di animazione e illustrazione con sede a Barcellona. Nel 2020 ha pubblicato il suo primo libro illustrato per bambini &#8216;P ha perso una storia&#8217; con Edizioni Clichy. Ama i colori e le forme semplici, i meme dei gattini e, naturalmente, mangiare spaghetti.&#8221; social_link_1=&#8221;instagram.com\/biancaspino&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7191&#8243; bio_alt_image_url=&#8221;7193&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Juan Huarte&#8221; job_position=&#8221;Workshop: Animazione al dente&#8221; team_member_bio=&#8221;Juan Huarte \u00e8 un animatore nomade che viene dall&#8217;argentina e negli ultimi anni raccoglie nuove esperienze in giro per l&#8217;Europa. Adora viaggiare e alterna la sua attivit\u00e0 da freelance con il suo lavoro da animatore per Arts &amp; Graft a Londra.&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/juanhuartwork&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7195&#8243; bio_alt_image_url=&#8221;6713&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Andrea Rauch&#8221; job_position=&#8221;Prezentazione del libro&#8221; team_member_bio=&#8221;Andrea Rauch ha disegnato manifesti, progettato mostre e illustrato libri. Ha disegnato grafica per istituzioni quali la Biennale di Venezia, il Centre Georges Pompidou, l&#8217;Unione dei Teatri d&#8217;Europa, Greenpeace e Unicef. Cofondatore dello studio di progettazioni visive Graphiti (Firenze, 1983-1993), tra il 1975 e il 1989 ha partecipato, insieme al socio Stefano Rovai, al movimento Grafica di pubblica utilit\u00e0. Nella sua carriera professionale Rauch ha disegnato pi\u00f9 di 700 manifesti che fanno parte delle collezioni del MoMA di New York, del Mus\u00e9e de la Publicit\u00e9 di Parigi e del Museum f\u00fcr Gestaltung di Zurigo.Ha insegnato Grafica presso il Corso di Laurea in Scienze della Comunicazione dell&#8217;Universit\u00e0 di Siena e Storia della Grafica all&#8217;Istituto Europeo di Design di Firenze.&#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7641&#8243; bio_alt_image_url=&#8221;7639&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Shrishti Vajpai&#8221; job_position=&#8221;TypeCampus e la community del type: dire, fare, studiare&#8221; team_member_bio=&#8221;Shrishti Vajpai \u00e8 una graphic designer, amante del caff\u00e8, appassionata dei dolci e un&#8217;ardente sognatrice, di Nuova Delhi, India. Dopo essersi laureata nel 2010 al College of Art Delhi, con un BFA Applied Art, ha iniziato a lavorare con importanti studi di graphic design seguendo la sua passione. Nel 2017, ha seguito un corso estivo in design dell&#8217;identit\u00e0, presso il Rhode Island Institute of Design, per approfondire le sue capacit\u00e0 e la comprensione. Nel 2020 ha conseguito il Master in Graphic Design (Focus on New Media) presso IED-Firenze, e si \u00e8 laureata con 110\/110 e lode.<br \/>\nIl suo obiettivo principale \u00e8 il branding, la strategia visiva e la comunicazione grafica. Le piace concettualizzare le idee e dare vita ai marchi. Ogni marchio ha una voce e lei si sforza di mettere insieme il linguaggio attraverso il quale racconta la sua storia, con il design come vocabolario. Con un&#8217;esperienza di oltre 8 anni in questo campo, ha lavorato nei settori Fashion, Lifestyle, Hospitality, Events, F&amp;B e Real Estate. Oltre al design, \u00e8 anche attratta dalla moda, dalla fotografia e dai viaggi.&#8221; social_link_1=&#8221;https:\/\/www.shrishtivajpai.com\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7199&#8243; bio_alt_image_url=&#8221;6288&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Elisa Basiissi | Calimaia Colletivo&#8221; job_position=&#8221;Talk: Calimaia in the city&#8221; team_member_bio=&#8221;Calimaia collettivo \u00e8 una rete di giovani professionisti grafici ed illustratori che organizza eventi creativi, come workshop, mostre collettive, live painting e chi pi\u00f9 ne ha pi\u00f9 ne metta! Collettivo per noi significa scambio e collaborazione: Calimaia nasce con il fine di creare un punto di incontro fra i professionisti creativi e dare loro visibilit\u00e0 attraverso l\u2019organizzazione di eventi sul territorio di Firenze e non solo!&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/calimaia_collettivo\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7277&#8243; bio_alt_image_url=&#8221;7275&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Francesco Ciaponi&#8221; job_position=&#8221;Panel: Only the Brave Quanto coraggio ci vuole per fare editoria indipendente nel 2021? Lungarno, Contrabbandiera Editrice e Friscospeaks presentano le propria realt\u00e0 esponendo le varie sfaccettature del mondo dell\u2019editoria indipendente&#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Francesco Ciaponi, laureato in Storia della stampa e dell&#8217;editoria all&#8217;Universit\u00e0 di Pisa con una tesi dal titolo \u201cBeat World: l&#8217;ascesa dell&#8217;editoria clandestina in Italia\u201d.<br \/>\nNel 2010 istituisce, insieme ad Andrea Pacini, Italian Poster Rock Art, l&#8217;archivio italiano di poster art.<br \/>\nDal 2016 gestisce il sito web di Edizioni del Frisco, che dal 2017 diventa una casa editrice specializzata in libri di grafica ed editoria indipendente.<br \/>\nNel 2019 ha dato vita, in collaborazione con Concretipo Studio, al progetto del magazine Friscospeaks, una jam session di grafici dalla chiara anima underground.<br \/>\nHa pubblicato diversi libri, tra cui: \u201cThe Big Lebowski Art Collection\u201d e \u201cUnderground: ascesa e caduta di un&#8217;altra pubblicazione\u201d.<br \/>\nNel 2019 \u00e8 stato pubblicato da Goodfellas il suo ultimo libro \u201cJack: una biografia illustrata\u201d; la prima biografia del famoso attore mai scritta in italiano.&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7281&#8243; bio_alt_image_url=&#8221;7279&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Matilde Sereni&#8221; job_position=&#8221;Panel: Only the Brave Quanto coraggio ci vuole per fare editoria indipendente nel 2021? Lungarno, Contrabbandiera Editrice e Friscospeaks presentano le propria realt\u00e0 esponendo le varie sfaccettature del mondo dell\u2019editoria indipendente&#8221; social_link_1=&#8221;https:\/\/www.lungarnofirenze.it\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Lungarno \u00e8 arrivato nel panorama cittadino nel 2012 diventando in poco tempo un prezioso strumento di navigazione per l\u2019offerta culturale della citt\u00e0. Da subito la rivista \u00e8 riuscita ad emergere per l\u2019alta qualit\u00e0 del prodotto nonostante la gratuit\u00e0 al pubblico: la scelta della carta usomano, un formato ampio e ben leggibile, una distribuzione capillare, contenuti originali, leggeri e professionali. Ma pi\u00f9 di ogni altro aspetto, a spianare la strada sono state le copertine illustrate; ogni mese un soggetto nuovo, una matita diversa, una visione della citt\u00e0 unica, uno stile personale: tutto questo ha fatto di Lungarno una rivista di cui fidarsi; sempre uguale e sempre diversa.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7285&#8243; bio_alt_image_url=&#8221;7283&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Tommaso Bovo&#8221; job_position=&#8221;Outside the box: Panel su collaborazioni tra docenti+studenti con Tommaso Bovo, Susanna Cerri, Laura Moretti&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Tommaso Bovo si occupa di grafica, packaging e tipografia. \u00c8 stato graphic designer e art director per gli studi Cisotti Laube, Archea Associati e Studio Doni &amp; Associati. Ha lavorato per le riviste Area, Materia e d\u2019Architettura. Fonda nel 2015 Tommaso Bovo \u2013 Studio di grafica. Ha tenuto lezione presso l\u2019Universit\u00e0 degli Studi di Firenze Facolt\u00e0 di Architettura, ha insegnato presso l\u2019Universit\u00e0 della Repubblica di San Marino facolt\u00e0 di Design, \u00e8 attualmente professore presso l\u2019Istituto Europeo di Design \u2013 IED nei corsi di Graphic Design e Metodologia del Progetto. Scrive per Domus, Frizzifrizzi, INTERNI, Artribune, Klat Magazine: si occupa di grafica, comunicazione e critica di design del prodotto. Ha vinto nel 2016 il Premio Treccani Web dedicato ai migliori articoli selezionati dalla redazione Treccani per \u201cqualit\u00e0 ed innovazione\u201d.&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7203&#8243; bio_alt_image_url=&#8221;7201&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Pierfilippo Ariano | BeFamily&#8221; job_position=&#8221;UI\/UX: Design Thinking workshop&#8221; team_member_bio=&#8221;Pierfilippo Ariano: Digital Art Director di Be.Family, un\u2019 agenzia con sede a Venezia e Firenze. Con oltre 10 anni di esperienza nella creazione di prodotti digitali, il suoi progetti sono un mix di differenti discipline: Product Design, Editorial Design, UX Design.<br \/>\nDal 2019 \u00e8 Sketch Advocate per l&#8217;Italia e docente di UI\/UX Design presso IUSVE &#8211; Universit\u00e0 di design della comunicazione a Venezia e Verona.&#8221; social_link_1=&#8221;dribbble.com\/PFLRN&#8221; social_link_2=&#8221;linkedin.com\/in\/pierfilippoariano&#8221; social_link_3=&#8221;behance.com\/pflrn&#8221; social_icon_1=&#8221;fa fa-dribbble&#8221; social_icon_2=&#8221;fa fa-linkedin-square&#8221; social_icon_3=&#8221;fa fa-behance-square&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7645&#8243; bio_alt_image_url=&#8221;7643&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Isabella Ahmadzadeh&#8221; job_position=&#8221;TypeCampus e la community del type: dire, fare, studiare&#8221; social_link_1=&#8221;https:\/\/ahmadzadeh.it&#8221; team_member_bio=&#8221;Isabella Ahmadzadeh \u00e8 una graphic designer multidisciplinare con focus sull\u2019illustrazione e il design 3d.<br \/>\nDopo essersi diplomata allo IED di Firenze in Comunicazione Pubblicitaria ha lavorato come graphic designer per Gucci, specializzandosi in art direction fotografica, e come art director per diverse aziende e studi grafici a Milano e Firenze, tra cui RovaiWeber.<br \/>\nIl suo lavoro tipografico Napo&amp;Leon \u00e8 stato selezionato da AWDA &#8211; Aiap Women in Design Award 2017, mentre le illustrazioni di Kitten hanno contribuito alla selezione di Zetafonts per i Typography &amp; Lettering Awards 2016 di Print Magazine.<br \/>\n\u00c8 stata selezionata in shortlist per il contest promosso da Why Festival Physically distant &#8211; Socially connected.<br \/>\nDall\u2019autunno 2019 \u00e8 coordinatrice del master di Graphic Design per IED (Istituto Europeo di Design) Firenze. Lavora attualmente per Zetafonts.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7207&#8243; bio_alt_image_url=&#8221;6274&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Simone Massoni&#8221; job_position=&#8221;Talk: Hearing You&#8221; team_member_bio=&#8221;Simone Massoni \u00e8 un visual artist adottato da Firenze da pi\u00f9 di vent\u2019anni ormai, si (pre)occupo di tutto ci\u00f2 che trove visivamente stimolante. Dopo avere cominciato la sua carriera come illustratore di libri per bambini ha virato i suoi interessi pi\u00f9 in generale verso l\u2019arte e il visual design. Potete trovare le sue ultime esplorazioni in libri, riviste, pubblicit\u00e0 e mostre principalmente in Nord America ed Europa. Ha collaborato con The New Yorker, The New York Times, Ferragamo, Facebook e molti altri clienti pi\u00f9 e meno illustri.&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/simonemassoni\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7240&#8243; bio_alt_image_url=&#8221;7238&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Maria Chiara Fantini&#8221; job_position=&#8221;Talk: Hearing You&#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Maria Chiara \u00e8 una designer e lettering artist basata a Firenze, dove vive e lavora. Le sue creazioni eleganti e intricate sono profondamente influenzate dal suo amore per la storia dell\u2019arte: in particolare ama guardare alla raffinatezza del Rinascimento fiorentino e alle opere decorative dei designer del movimento Arts and Crafts.&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7248&#8243; bio_alt_image_url=&#8221;7246&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Susanna Cerri&#8221; job_position=&#8221;Outside the box: Panel su collaborazioni tra docenti+studenti con Tommaso Bovo, Susanna Cerri, Laura Moretti&#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Susanna Cerri \u00e8 un docente presso il Dipartimento di Architettura dell\u2019Universit\u00e0 degli Studi di Firenze. Direttore Creativo del Laboratorio di Comunicazione del Dipartimento di Architettura, che cura la comunicazione e di progettazione editoriale a livello di Dipartimento e di Ateneo. Socio Professionista Designer della Comunicazione Senior di AIAP Associazione Italiana Design della Comunicazione Visiva, attiva in tutti gli ambiti della comunicazione pubblica e privata dal 1984. Fin dal conseguimento della laurea ho svolto attivit\u00e0 di ricerca, professionale, e di formazione nel settore del communication design, del design editoriale, della comunicazione istituzionale e del packaging. Attualmente mi occupo prevalentemente di graphic design per l\u2019editoria scientifica e di progetti sulla relazione tra grafica e spazio pubblico. Negli ultimi anni ho indirizzato la mia ricerca sui temi del social design stringendo collaborazioni con una rete internazionale di universit\u00e0.&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7273&#8243; bio_alt_image_url=&#8221;7271&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Laura Moretti&#8221; job_position=&#8221;Outside the box: Panel su collaborazioni tra docenti+studenti con Tommaso Bovo, Susanna Cerri, Laura Moretti&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Laura Moretti \u00e8 fondatrice e direttrice creativa dello Studio Laura Moretti. Dal 2004 svolge attivit\u00e0 di docenza in grafica pubblicitaria, comunicazione visiva e visual merchandising presso vari Istituti di livello universitario. Insieme a Cinzia Ferrara e Daniela Piscitelli ha fondato il premio Aiap Women in Design Award, ora nella sua terza edizione. Questo premio biennale ha l\u2019intento di comprendere e promuovere l\u2019universo delle donne legato al design della comunicazione visiva, spesso poco conosciuto, e il loro contributo alla diffusione della cultura del progetto.&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7258&#8243; bio_alt_image_url=&#8221;7256&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Camilla Pieri&#8221; job_position=&#8221;Talk: Illustrazione tra culturale e sociale&#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Camilla Pieri si occupa di eventi, cultura e comunicazione: alla costante ricerca di tutto ci\u00f2 che ama definire \u201caltamente improbabile\u201d, si perde in brochure, font e significati, amante della ricerca costante di sensi e con un forte attaccamento al sociale. Nel 2019 fonda, insieme a Claudia Pasquini e Olivia Balestrino, Collettivo Loredana: un collettivo che si occupa di promuovere il talento, la creativit\u00e0 e il network tra donne che fanno arte.&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7262&#8243; bio_alt_image_url=&#8221;7266&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Luchadora &#8211; Alessandra Marianelli&#8221; job_position=&#8221;Talk: Illustrazione tra culturale e sociale&#8221; social_link_1=&#8221;www.luchadora.it&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Luchadora, nome d\u2019arte di Alessandra Marianelli, \u00e8 un\u2019artista e designer multidisciplinare poliedrica le cui opere esplorano l\u2019arte attraverso un ampio spettro di strumenti, che coinvolgono l\u2019illustrazione, la grafica e la pittura. Il suo nome d\u2019arte \u00e8 ispirato alle lottatrici del wrestling messicano, dalle quali l\u2019artista ha sempre trovato affascinanti la vivacit\u00e0 dei colori, la fantasia delle loro caratteristiche maschere e la grande energia positiva. Ha una borsa di ricerca presso l\u2019universit\u00e0 di architettura di Firenze e si occupa di illustrazione e grafica da freelance (le ultime campagne di comunicazione che ha curato sono per Activia-Danone e Anlaids-onlus).&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7254&#8243; bio_alt_image_url=&#8221;7268&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Gionatella &#8211; Gionatan Fiondella&#8221; job_position=&#8221;Talk: Illustrazione tra culturale e sociale&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/gionatella_\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Gionatella-Gionatan Fiondella \u00e8 un Illustratore e attivista, qui \u00e8 cresciuto a Latina e contestualmente agli studi per diventare Illustratore si avvicina alla militanza politica, da prima sul suo territorio poi su Roma. Tramite il Queer Fest di Latina conosco i Conigli Bianchi un collettivo di artivist* che usa l\u2019arte per la divulgazione di temi legati al safer sex con un focus su HIV e stigma.<br \/>\nNel collettivo, che \u00e8 diventata la sua casa politica, si \u00e8 da subito occupato principalmente di comunicazione e design avendo il piacere di lavorare con moltissime associazioni italiane, partecipando alla costruzione di eventi e campagne di comunicazione, fra cui: Anlaids, Lila, Circolo di cultura omosessuale Mario Mieli, Arcigay, Asa, Milano checkpoint, SWIPE, Ombrerosse e altre.&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7617&#8243; bio_alt_image_url=&#8221;7615&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Nicola Giorgio&#8221; job_position=&#8221;Live drawing&#8221; social_link_1=&#8221;http:\/\/www.nicolagiorgio.com\/&#8221; social_link_2=&#8221;https:\/\/www.instagram.com\/mauro_bubbico\/&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Nicola Giorgio \u00e8 un freelance illustratore con una base a Florence. Fa parte di Muttnik collectivo.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_icon_2=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7629&#8243; bio_alt_image_url=&#8221;7627&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Erika Gabbani&#8221; job_position=&#8221;Talk 2021 Networking come progetto per l\u2019arte, da Gruppo11 a Drawingalive&#8221; social_link_1=&#8221;www.nasonero.com&#8221; social_link_2=&#8221;www.erikaconlak.it&#8221; social_link_3=&#8221;www.drawingalive.net&#8221; team_member_bio=&#8221;Erika Gabbani lavora come freelance per la comunicazione e l&#8217;arte con lo Studio Nasonero che ha co-fondato con il marito Daniele Tabellini. Si occupa dell&#8217;ideazione, progettazione e realizzazione di numerosi progetti e organizza allestimenti, mostre e relazioni con clienti, collaboratori ed enti pubblici.<\/p>\n<p>Usa l&#8217;approccio alle arti visive e alle tecniche creative e di visualizzazione per organizzare, seguire e migliorare lo sviluppo e l&#8217;autonomia degli studenti.<\/p>\n<p>\u00c8 curatrice d&#8217;arte contemporanea indipendente dal 2000 tra Crespina, Roma, Citt\u00e0 del Messico e Firenze. Tra le tante, il festival Drawing (a)live a Citt\u00e0 del Messico, Oaxaca e Viareggio, il festival CresperimentArt sulle colline pisane e le mostre allo Studio Fupete di Roma. \u00c8 consulente artistica, ha ideato e curato laboratori su arte e creativit\u00e0, ha tenuto conferenze e Accompagnatore turistico in universit\u00e0 e festival, per bambini e adulti.<\/p>\n<p>\u00c8 la met\u00e0 del duo di artisti Teller &amp; K (fino al 2016 conosciuto come Fupete). La loro ricerca spazia tra installazioni, design e performance, digitale e non digitale&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_icon_2=&#8221;fa fa-chain-broken&#8221; social_icon_3=&#8221;fa fa-chain-broken&#8221; social_icon_4=&#8221;fa fa-chain-broken&#8221; social_link_4=&#8221;www.tellerk.com&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7625&#8243; bio_alt_image_url=&#8221;7623&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Daniele Tabellini&#8221; job_position=&#8221;Talk 2021 Networking come progetto per l\u2019arte, da Gruppo11 a Drawingalive&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Condivide con la moglie Erika Gabbani lo studio di comunicazione e arte nasonero.studio, e la pratica di ricerca artistica tellerk.com. Dal 2013 al 2020 \u00e8 stato art director di Lcd a Firenze, dove il suo lavoro nel 2015 ha ricevuto una Menzione d\u2019Onore al Compasso d\u2019Oro International Award. \u00c8 stato promotore e membro dello Steering Committee per le Linee Guida di Design per i Siti Web della PA. Da ottobre 2020 ha un incarico come esperto UI\/UX designer presso il Dipartimento per la Trasformazione Digitale della Presidenza del Consiglio dei Ministri. Dal 2013 tiene laboratori di interaction design avanzato per la laurea magistrale a UNIRSM Design, Universit\u00e0 della Repubblica di San Marino.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_link_1=&#8221;https:\/\/nasonero.studio\/&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][team_member image_url=&#8221;7621&#8243; bio_alt_image_url=&#8221;7619&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Paola Lucrezzi&#8221; job_position=&#8221;Linocut per illustratori&#8221; social_link_1=&#8221;https:\/\/www.ilbisonte.it\/&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Il workshop di Linocut \u00e8 organizzato dalla Fondazione Il Bisonte, storica realt\u00e0 fiorentina che dal 1959 si occupa di grafica d\u2019arte; offre una grande variet\u00e0 di corsi pratici; ospita artisti in residenza; organizza mostre ed eventi; possiede una biblioteca con pi\u00f9 di tremila volumi e custodisce una collezione consultabile di pi\u00f9 di cinquemila stampe.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][team_member image_url=&#8221;7633&#8243; bio_alt_image_url=&#8221;7631&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Missive Selvatiche&#8221; job_position=&#8221;Una resistenza artistica&#8221; social_link_1=&#8221;https:\/\/www.instagram.com\/Missiveselvatiche&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Missive Selvatiche \u00e8 un progetto di resistenza artistica nato a Prato nel novembre 2020 in seguito alle restrizioni sanitarie che hanno portato alla chiusura di tutti gli spazi legati alla cultura, all\u2019arte e allo spettacolo dal vivo.<br \/>\nll progetto nasce da un\u2019idea di Pamela Maddaleno, Alessia Castellano e Margherita Nuti e mira ad innescare una serie di riflessioni: cosa accade quando un\u2019opera esce dal canonico percorso che va dall\u2019autore al fruitore che si suppone essere interessato a quel tipo specifico di opera? Cosa accade se un\u2019opera viene trovata in un luogo dove non dovrebbe trovarsi, come una cassetta della posta? Cosa accade se si riceve un regalo non richiesto? E cosa accade se un artista mette la propria opera nelle mani del caso, se non sa pi\u00f9 chi sono i fruitori e non \u00e8 pi\u00f9 certo di ricevere un riscontro da questi ultimi?&#8221; social_icon_1=&#8221;fa fa-instagram&#8221;][\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][team_member image_url=&#8221;7637&#8243; bio_alt_image_url=&#8221;7635&#8243; team_memeber_style=&#8221;bio_fullscreen_alt&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Debora Manetti&#8221; job_position=&#8221;TypeCampus e la community del type: dire, fare, studiare&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221; team_member_bio=&#8221;Debora Manetti, Insieme a Francesco Canovaro e Cosimo Lorenzo Pancini, \u00e8 fondatrice e creative director di Ligature Srl e Studio Kmzero. Entrambi i brand si occupano, in maniera complementare, di cultura del branding e tipografia, per il mercato internazionale e locale.&#8221; social_icon_1=&#8221;fa fa-chain-broken&#8221; social_link_1=&#8221;https:\/\/www.zetafonts.com\/&#8221;][\/team_member][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;Partners&#8221; max_width=&#8221;500&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;6161&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/www.thestudenthotel.com\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;6150&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tshcollab.com&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;6159&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;www.befamily.it&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;7309&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/www.wacom.com\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;7307&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/www.museomagma.com\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;6537&#8243; animation=&#8221;Grow In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/www.the-district.com&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2dc8e1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#ffffff&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;Want to be part of WHY Festival?Drop us an email!&#8221;][\/split_line_heading][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;right&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; text_color=&#8221;#ffffff&#8221; button_color=&#8221;extra-color-2&#8243; link_type=&#8221;new_tab&#8221; alignment=&#8221;right&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;inline&#8221; url=&#8221;mailto:info@whyfestival.com&#8221; padding_top=&#8221;20&#8243; padding_right=&#8221;40&#8243; padding_bottom=&#8221;20&#8243; padding_left=&#8221;40&#8243; link_text=&#8221;Contact us&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;6024&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;13%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; color_overlay=&#8221;rgba(10,10,10,0)&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;350&#8243; bg_image_animation=&#8221;fade-in&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-7832","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/pages\/7832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/comments?post=7832"}],"version-history":[{"count":2,"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/pages\/7832\/revisions"}],"predecessor-version":[{"id":7835,"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/pages\/7832\/revisions\/7835"}],"wp:attachment":[{"href":"https:\/\/whyfestival.com\/it\/wp-json\/wp\/v2\/media?parent=7832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}